{"id":2626,"date":"2016-01-05T09:24:17","date_gmt":"2016-01-05T11:24:17","guid":{"rendered":"http:\/\/nivaldocleto.cnt.br\/blog\/?p=2626"},"modified":"2024-02-01T09:24:31","modified_gmt":"2024-02-01T12:24:31","slug":"ces-2016","status":"publish","type":"post","link":"https:\/\/nivaldocleto.cnt.br\/blog\/ces-2016\/","title":{"rendered":"CES 2016"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-70e38eagsq\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-2-col\"  data-pid=\"2650\"><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/nivaldocleto.cnt.br\/blog\/ces-2016-dia-10-de-janeiro\/\" class=\"_self cvplbd\" target=\"_self\" >CES 2016 &#8211; Dia 10 de janeiro<\/a><\/h4>\n<div class=\"pt-cv-content\">Startups s\u00e3o destaque no \u00faltimo dia da CES 2016 Hoje vamos falar direto do \u202aEureka Park, que desde o ano ...<br \/><a href=\"https:\/\/nivaldocleto.cnt.br\/blog\/ces-2016-dia-10-de-janeiro\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\">Leia Mais<\/a><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-2-col\"  data-pid=\"2648\"><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/nivaldocleto.cnt.br\/blog\/ces-2016-dia-9-de-janeiro\/\" class=\"_self cvplbd\" target=\"_self\" >CES 2016 &#8211; Dia 9 de janeiro<\/a><\/h4>\n<div class=\"pt-cv-content\">Terceiro dia de inova\u00e7\u00f5es na CES 2016 Imers\u00e3o, compatibilidade e autonomia s\u00e3o os temas predominantes. A Sony d\u00e1 seu show ...<br \/><a href=\"https:\/\/nivaldocleto.cnt.br\/blog\/ces-2016-dia-9-de-janeiro\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\">Leia Mais<\/a><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-2-col\"  data-pid=\"2645\"><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/nivaldocleto.cnt.br\/blog\/ces-2016-dia-8-de-janeiro\/\" class=\"_self cvplbd\" target=\"_self\" >CES 2016 &#8211; Dia 8 de janeiro<\/a><\/h4>\n<div class=\"pt-cv-content\">Inova\u00e7\u00f5es do segundo dia da CES 2016 Hoje vamos continuar trazendo o que esta feira tem de melhor. No pavilh\u00e3o ...<br \/><a href=\"https:\/\/nivaldocleto.cnt.br\/blog\/ces-2016-dia-8-de-janeiro\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\">Leia Mais<\/a><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-2-col\"  data-pid=\"2642\"><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/nivaldocleto.cnt.br\/blog\/ces-2016-dia-7-de-janeiro\/\" class=\"_self cvplbd\" target=\"_self\" >CES 2016 &#8211; Dia 7 de janeiro<\/a><\/h4>\n<div class=\"pt-cv-content\">Mobilidade \u00e9 destaque na abertura da CES 2016 E come\u00e7a a CES 2016! Nesta quarta-feira foi a abertura da feira ...<br \/><a href=\"https:\/\/nivaldocleto.cnt.br\/blog\/ces-2016-dia-7-de-janeiro\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\">Leia Mais<\/a><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-2-col\"  data-pid=\"2634\"><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/nivaldocleto.cnt.br\/blog\/ces-2016-dia-6-de-janeiro\/\" class=\"_self cvplbd\" target=\"_self\" >CES 2016 &#8211; Dia 6 de janeiro<\/a><\/h4>\n<div class=\"pt-cv-content\">Gigantes apresentam suas novidades Nesta ter\u00e7a-feira (05) a CES 2016 realizou um evento para a imprensa e convidados para apresentar ...<br \/><a href=\"https:\/\/nivaldocleto.cnt.br\/blog\/ces-2016-dia-6-de-janeiro\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\">Leia Mais<\/a><\/div><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-2-col\"  data-pid=\"2629\"><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/nivaldocleto.cnt.br\/blog\/ces-2016-dia-5-de-janeiro\/\" class=\"_self cvplbd\" target=\"_self\" >CES 2016 &#8211; Dia 5 de janeiro<\/a><\/h4>\n<div class=\"pt-cv-content\">Seguran\u00e7a digital ser\u00e1 uma das tend\u00eancias na CES 2016 Ter\u00e1 in\u00edcio nesta quarta-feira (06), em Las Vegas, EUA, a feira ...<br \/><a href=\"https:\/\/nivaldocleto.cnt.br\/blog\/ces-2016-dia-5-de-janeiro\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\">Leia Mais<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-3798fe3ah5\">#pt-cv-view-70e38eagsq .pt-cv-ifield { padding-top: 10px !important; padding-left: 10px !important; padding-right: 10px !important; }\n#pt-cv-view-70e38eagsq  .pt-cv-ifield   { background-color: #f7f7f7 !important; }\n#pt-cv-view-70e38eagsq .pt-cv-title a, #pt-cv-view-70e38eagsq  .panel-title { color: #a40731 !important; font-weight: 600 !important; }\n#pt-cv-view-70e38eagsq .pt-cv-carousel-caption  { background-color: rgba(51,51,51,.6) !important; }\n#pt-cv-view-70e38eagsq .pt-cv-specialp { background-color: #CC3333 !important }\n#pt-cv-view-70e38eagsq .pt-cv-specialp * { color: #fff !important; }\n#pt-cv-view-70e38eagsq .pt-cv-pficon  { color: #bbb !important; }\n#pt-cv-view-70e38eagsq .pt-cv-readmore  { color: #ffffff !important; background-color: #747c87 !important; }\n#pt-cv-view-70e38eagsq .pt-cv-readmore:hover  { color: #ffffff !important; background-color: #a40731 !important; }\n#pt-cv-view-70e38eagsq  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-70e38eagsq  + .pt-cv-pagination-wrapper .pagination .active a { color: #ffffff !important; background-color: #00aeef !important; }<\/style>\r\n\t\t\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2627,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-2626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos"],"_links":{"self":[{"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/posts\/2626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/comments?post=2626"}],"version-history":[{"count":1,"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/posts\/2626\/revisions"}],"predecessor-version":[{"id":2628,"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/posts\/2626\/revisions\/2628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/media\/2627"}],"wp:attachment":[{"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/media?parent=2626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/categories?post=2626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/tags?post=2626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}