{"id":1453,"date":"2020-01-10T14:09:49","date_gmt":"2020-01-10T17:09:49","guid":{"rendered":"http:\/\/nivaldocleto.cnt.br\/blog\/?p=1453"},"modified":"2020-01-30T18:37:59","modified_gmt":"2020-01-30T21:37:59","slug":"robot-walker","status":"publish","type":"post","link":"https:\/\/nivaldocleto.cnt.br\/blog\/robot-walker\/","title":{"rendered":"Robot &#8220;Walker&#8221;"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>A UBTECH Robotics anunciou na CES2020 uma grande atualiza\u00e7\u00e3o para um rob\u00f4 ambulante demonstrado pela primeira vez na CES 2018. O Walker ganhou um torso, bra\u00e7os, m\u00e3os e cabe\u00e7a e agora \u00e9 t\u00e3o human\u00f3ide quanto os rob\u00f4s b\u00edpedes.<\/p>\n<p>\u201cWalker \u00e9 seu companheiro \u00e1gil e inteligente &#8211; um rob\u00f4 human\u00f3ide b\u00edpede inteligente que visa um dia ser uma parte indispens\u00e1vel de sua fam\u00edlia. Com 1,45 m de altura e 77 kg de peso, a nova vers\u00e3o do Walker est\u00e1 mais avan\u00e7ada do que nunca, incluindo bra\u00e7os e m\u00e3os com a capacidade de agarrar e manipular objetos, um torso refinado com melhor equil\u00edbrio pr\u00f3prio, caminhada suave e est\u00e1vel em ambientes dif\u00edceis e intera\u00e7\u00e3o multimodal, incluindo voz, vis\u00e3o e toque. A Walker possui 36 atuadores de alto desempenho e uma gama completa de sistemas de sensores que trabalham juntos para garantir uma caminhada suave e r\u00e1pida\u201d, disse a empresa.<\/p>\n<p>Lembra do desenho The Jetsons? Pois \u00e9!<\/p>\n<p><iframe loading=\"lazy\" title=\"CES2020 - Human\u00f3ide da UBTECH Robotics\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/2s1BWp1m5JY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-1454\" src=\"http:\/\/nivaldocleto.cnt.br\/blog\/wp-content\/uploads\/2020\/01\/82233635_10221393224610406_7997197919394463744_o.jpg\" alt=\"Robot &quot;Walker&quot;\" width=\"90%\" height=\"auto\" srcset=\"https:\/\/nivaldocleto.cnt.br\/blog\/wp-content\/uploads\/2020\/01\/82233635_10221393224610406_7997197919394463744_o.jpg 712w, https:\/\/nivaldocleto.cnt.br\/blog\/wp-content\/uploads\/2020\/01\/82233635_10221393224610406_7997197919394463744_o-232x300.jpg 232w\" sizes=\"(max-width: 712px) 100vw, 712px\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-1455\" src=\"http:\/\/nivaldocleto.cnt.br\/blog\/wp-content\/uploads\/2020\/01\/82110239_10221393224730409_5739803889331339264_o.jpg\" alt=\"Robot &quot;Walker&quot;\" width=\"90%\" height=\"auto\" srcset=\"https:\/\/nivaldocleto.cnt.br\/blog\/wp-content\/uploads\/2020\/01\/82110239_10221393224730409_5739803889331339264_o.jpg 720w, https:\/\/nivaldocleto.cnt.br\/blog\/wp-content\/uploads\/2020\/01\/82110239_10221393224730409_5739803889331339264_o-169x300.jpg 169w, https:\/\/nivaldocleto.cnt.br\/blog\/wp-content\/uploads\/2020\/01\/82110239_10221393224730409_5739803889331339264_o-576x1024.jpg 576w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-1456\" src=\"http:\/\/nivaldocleto.cnt.br\/blog\/wp-content\/uploads\/2020\/01\/82122007_10221393224490403_1842510471421231104_o.jpg\" alt=\"Robot &quot;Walker&quot;\" width=\"90%\" height=\"auto\" srcset=\"https:\/\/nivaldocleto.cnt.br\/blog\/wp-content\/uploads\/2020\/01\/82122007_10221393224490403_1842510471421231104_o.jpg 720w, https:\/\/nivaldocleto.cnt.br\/blog\/wp-content\/uploads\/2020\/01\/82122007_10221393224490403_1842510471421231104_o-169x300.jpg 169w, https:\/\/nivaldocleto.cnt.br\/blog\/wp-content\/uploads\/2020\/01\/82122007_10221393224490403_1842510471421231104_o-576x1024.jpg 576w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A UBTECH Robotics anunciou na CES2020 uma grande atualiza\u00e7\u00e3o para um rob\u00f4 ambulante demonstrado pela primeira vez na CES 2018. O Walker ganhou um torso, bra\u00e7os, m\u00e3os e cabe\u00e7a e agora \u00e9 t\u00e3o human\u00f3ide quanto os rob\u00f4s b\u00edpedes. \u201cWalker \u00e9 seu companheiro \u00e1gil e inteligente &#8211; um rob\u00f4 human\u00f3ide b\u00edpede inteligente que visa um dia ser uma parte indispens\u00e1vel de sua fam\u00edlia. Com 1,45 m de altura e 77 kg de peso, a nova vers\u00e3o do Walker est\u00e1 mais avan\u00e7ada do que nunca, incluindo bra\u00e7os e m\u00e3os com a capacidade de agarrar e manipular objetos, um torso refinado com melhor equil\u00edbrio pr\u00f3prio, caminhada suave e est\u00e1vel em ambientes dif\u00edceis e intera\u00e7\u00e3o multimodal, incluindo voz, vis\u00e3o e toque. A Walker possui 36 atuadores de alto desempenho e uma gama completa de sistemas de sensores que trabalham juntos para garantir uma caminhada suave e r\u00e1pida\u201d, disse a empresa. Lembra do desenho The Jetsons? Pois \u00e9!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[24],"class_list":["post-1453","post","type-post","status-publish","format-standard","hentry","category-cess2020","tag-ces2020"],"_links":{"self":[{"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/posts\/1453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/comments?post=1453"}],"version-history":[{"count":2,"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/posts\/1453\/revisions"}],"predecessor-version":[{"id":1535,"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/posts\/1453\/revisions\/1535"}],"wp:attachment":[{"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/media?parent=1453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/categories?post=1453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nivaldocleto.cnt.br\/blog\/wp-json\/wp\/v2\/tags?post=1453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}